{"id":628,"date":"2024-08-27T08:47:10","date_gmt":"2024-08-27T08:47:10","guid":{"rendered":"http:\/\/dev.novia-doors.com\/?page_id=628"},"modified":"2024-10-09T15:56:03","modified_gmt":"2024-10-09T15:56:03","slug":"up-and-over-garage-doors","status":"publish","type":"page","link":"https:\/\/dev.novia-doors.com\/en\/up-and-over-garage-doors\/","title":{"rendered":"Up and over garage doors"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;645&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-banner spy1&#8243; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#333333&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221; el_class=&#8221;smb-tiny&#8221;]\n<h5>For Home<\/h5>\n[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h1 class=\"Typography__H1-sc-1b3db1p-1 Herostyled__Title-sc-6ukaqh-5 fcmurD klHvLe\">Up and over garage doors<\/h1>\n[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221; el_class=&#8221;sub-heading&#8221;]They combine a reliable structure and simple installation with a broad range of solutions that you can tailor to your needs.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;spy1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221; max_width=&#8221;650&#8243;]\n<section id=\"intro\" class=\"Sectionstyled__Section-sc-8qjhr7-0 iXYDHV\">\n<div class=\"Container-sc-1kq3w73-0 TextAloneBlockstyled__Content-sc-ovx3cd-0 eHsvtH bHBJdb text-alone-component cm-animate cm-animate-opacity cm-animate-translate\">\n<div class=\"RichTextBlockstyled__Column-sc-g8h6c8-0 cgXpAz\">\n<p class=\"Typography__Text-sc-1b3db1p-0 RichTextBlockstyled__SizedText-sc-g8h6c8-2 qFIPW kTeDDj\">Up and over garage doors feature a simple, yet solid structure. Thanks to their reliability, they have enjoyed unwavering popularity for years. They are available with and without thermal insulation. A wide range of models and colours makes it possible to tailor the garage door to your own vision and expectations.<\/p>\n<\/div>\n<\/div>\n<\/section>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;page-inner-slider&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<style type=\"text\/css\">#nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { min-height: 400px; } #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: calc( 500 * 100vw \/ 1600 ); } <\/style><div data-midnight=\"nectar-slider\" class=\"parallax_slider_outer \"><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"true\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"7000\" data-parallax=\"true\" data-parallax-disable-mobile=\"true\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"ken_burns\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"500\" data-min-height=\"400\" data-arrows=\"false\" data-bullets=\"true\" data-bullet_style=\"see_through_ar_visualized\" data-bullet_position=\"right\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"60%\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"bottom\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/dev.novia-doors.com\/wp-content\/uploads\/2024\/08\/a5c8e7e8-53e3-4997-b846-12de8af3c2ff.jpg);\"> &nbsp; <\/div><div class=\"slide-bg-overlay\" style=\"background-color: #3a3d3f;\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h3 class=\"ns-heading-el\">Comprehensive range of accessories<\/h3><p  ><span>We combine quality and aesthetic appeal with affordable prices. The standard version of the garage door comes equipped with: a lock with a lock cylinder, a set of three keys, and an installation kit. This comprehensive range of accessories guarantees easy and effective installation.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"60%\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"bottom\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/dev.novia-doors.com\/wp-content\/uploads\/2024\/08\/bdc9884f-68e5-46e3-9214-7d813b63549d.jpg);\"> &nbsp; <\/div><div class=\"slide-bg-overlay\" style=\"background-color: #3a3d3f;\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h3 class=\"ns-heading-el\">A wide array of solutions<\/h3><p  ><span>You can opt for an insulated garage door if you want to keep your garage warm, a garage door with a wicket door if you need an additional entrance or a garage door with a renovation frame.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"60%\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"bottom\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/dev.novia-doors.com\/wp-content\/uploads\/2024\/08\/71ad069e-372a-451b-b7d3-70d1caabae60.jpg);\"> &nbsp; <\/div><div class=\"slide-bg-overlay\" style=\"background-color: #3a3d3f;\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h3 class=\"ns-heading-el\">Durability<\/h3><p  ><span>WI\u015aNIOWSKI up and over garage doors are a proven solution and a choice that will last for years. The structure made of galvanised steel sections and the leaf lining made of galvanised steel sheet with polyester coating guarantee high corrosion resistance.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"60%\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"bottom\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/dev.novia-doors.com\/wp-content\/uploads\/2024\/08\/21afaa3d-904e-41a8-84c7-5060d60e695c.jpg);\"> &nbsp; <\/div><div class=\"slide-bg-overlay\" style=\"background-color: #3a3d3f;\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h3 class=\"ns-heading-el\">Comfort of use<\/h3><p  ><span>Using the garage door is very easy and does not require much effort. The spring system used allows you to lift and lower the garage door without using much force. Adding a drive unit enables operation with the use of a remote or the smart function \u2013 with just one button in our smartphone app.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"container normal-container slider-pagination-wrap\"><div class=\"slider-pagination\"><\/div><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<p class=\"Typography__H3-sc-1b3db1p-3 GzJrR\" data-index=\"1\">Up and over garage doors<\/p>\n<h3>CONNECT up and over garage door<\/h3>\n<p>The CONNECT garage door combines simplicity and reliable structure with broad customization options.<\/p>\n<p>Choose this model if you are looking for an economical solution in good taste. The design of the CONNECT door resembles the style of sectional garage doors. The series offers a broad choice of original decorative motifs, colours, ribs, and accessories.<\/p>\n<p>You can also automate it and even connect it with a smartphone app to open and close the garage door from any place in the world.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;652&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;648&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;spt1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h3 class=\"Typography__H3-sc-1b3db1p-3 HeaderBlockstyled__Heading3-sc-hqwh3o-2 GzJrR\">Other models of up and over garage doors<\/h3>\n<p class=\"Typography__H3-sc-1b3db1p-3 HeaderBlockstyled__Heading3-sc-hqwh3o-2 GzJrR\">An up and over garage door does not have to meet the common stereotypes. Tailor the selected model to your needs, taking advantage of a broad range of designs, colours, glazings, and accessories.<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal&#8221;][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;KOMFORT&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<div class=\"AccordionComponentstyled__TitleWrapper-sc-17xtk59-0 pjuLf title-wrapper\"><\/div>\n<div class=\"AccordionComponentstyled__HiddenContentWrapper-sc-17xtk59-3 glasbY\">\n<div class=\"AccordionComponentstyled__HiddenContent-sc-17xtk59-4 kTAPvy\">\n<p class=\"Typography__Text-sc-1b3db1p-0 ImageSplitAccordionBlockstyled__CustomText-sc-1cbcc3b-4 ipiqhy ctrPWQ\">If the comfort of use and unique design is what matters to you, choose the KOMFORT garage door. It is a structure you can infill according to your own vision, for instance with wood or selected type of plastic. In this version, it looks truly exceptional!<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;NOVUM&#8221;][vc_column_text text_direction=&#8221;default&#8221;]A true WI\u015aNIOWSKI classic. A durable and proven standard model whose popularity has not wavered for more than 30 years! The leaf lining is made of galvanised steel sheet with a polyester coating. The simple and stable structure guarantees an optimal closure system for stand-alone garages.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;CITY&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<div class=\"AccordionComponentstyled__TitleWrapper-sc-17xtk59-0 pjuLf title-wrapper\"><\/div>\n<div class=\"AccordionComponentstyled__HiddenContentWrapper-sc-17xtk59-3 glasbY\">\n<div class=\"AccordionComponentstyled__HiddenContent-sc-17xtk59-4 kTAPvy\">\n<p class=\"Typography__Text-sc-1b3db1p-0 ImageSplitAccordionBlockstyled__CustomText-sc-1cbcc3b-4 ipiqhy ctrPWQ\">A proven closure system for terraced, underground, and stand-alone garages. Thanks to special ventilation holes and perforation, it ensures proper air exchange in the garage. The galvanised and coated leaf lining guarantees durability for many years.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;PROGRESS&#8221;][vc_column_text text_direction=&#8221;default&#8221;]It is a version of an up and over garage door that you can easily insulate with a PVC panel. You can also add a convenient wicket door. Garage safety is ensured by secure locking and the structure is reinforced by a practical crosspiece connecting the horizontal tracks.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;SELECT&#8221;][vc_column_text text_direction=&#8221;default&#8221;]The SELECT garage door is dedicated to customers who value a broad range of options and finishes. The opening frame in the door leaf colour guarantees unique aesthetic qualities. You can also complement the product with a warm PVC panel, wicket door, glazings, and ventilation grilles.[\/vc_column_text][\/toggle][\/toggles][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;635&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;spt1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h2>Up and over garage door models<\/h2>\n[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]Our up and over garage doors are available in as many as 16 versions. Select the design that will best match your building.[\/vc_column_text][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;3&#8243; desktop_small_cols_flickity=&#8221;3&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;touch_total&#8221; flickity_touch_total_style=&#8221;default&#8221; flickity_touch_total_hide_indicator=&#8221;true&#8221; flickity_touch_total_icon_color=&#8221;default&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086126-9&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086127-10&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;638&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Vertical infill, high V<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086170-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086171-3&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;654&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Horizontal infill, high H<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086261-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086262-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;631&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Vertical infill, low<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086302-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086303-1&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;634&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Horizontal infill, low<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086338-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086339-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;641&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Horizontal infill, high<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086379-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086380-10&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;653&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Vertical infill, high<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086413-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086414-4&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;632&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Vertical infill, high with a strip<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086438-1&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086439-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;644&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Horizontal infill, high with a strip<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086470-9&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086471-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;647&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Slanted infill, SV<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086500-2&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086501-5&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;636&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Slanted infill, SA<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086536-1&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086537-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;651&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Perforated infill, bottom<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086566-4&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086567-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;650&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Perforated infill, top<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086624-7&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086625-4&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;640&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Perforated infill, top-bottom<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086680-0&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086681-10&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;633&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Perforated infill<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086717-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086718-5&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;642&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Horizontal infill, low \u2013 shutter<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1724752086755-2&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1724752086756-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;643&#8243; image_aspect_ratio=&#8221;1-1&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;50vh&#8221; min_height_tablet=&#8221;550&#8243;]\n<h4>Horizontal infill, high \u2013 shutter<\/h4>\n[\/fancy_box][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h2>Colour scheme<\/h2>\n[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221; max_width=&#8221;650&#8243;]Match the garage door to the elevation, surroundings or other joinery elements. Choose from a timeless range of classic colours and film coatings. The DECOR colours are only available for the V and H models.[\/vc_column_text][tabbed_section style=&#8221;minimal&#8221; tab_change_animation=&#8221;fade&#8221; alignment=&#8221;left&#8221; spacing=&#8221;default&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; cta_button_style=&#8221;accent-color&#8221; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Film coatings, standard colours&#8221; id=&#8221;1724752086861-10&#8243; tab_id=&#8221;1724752086861-0&#8243;][image_with_animation image_url=&#8221;655&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;DECOR colours&#8221; id=&#8221;1724752161490-4&#8243; tab_id=&#8221;1724752161491-1&#8243;][image_with_animation image_url=&#8221;656&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/tab][\/tabbed_section][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;645&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-banner spy1&#8243; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#333333&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-628","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":29,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages\/628\/revisions"}],"predecessor-version":[{"id":691,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages\/628\/revisions\/691"}],"wp:attachment":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/media?parent=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}