{"id":1401,"date":"2024-09-11T08:43:01","date_gmt":"2024-09-11T08:43:01","guid":{"rendered":"http:\/\/dev.novia-doors.com\/?page_id=1401"},"modified":"2024-10-09T12:16:07","modified_gmt":"2024-10-09T12:16:07","slug":"creo-entrance-doors","status":"publish","type":"page","link":"https:\/\/dev.novia-doors.com\/en\/creo-entrance-doors\/","title":{"rendered":"CREO entrance doors"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1391&#8243; bg_image_phone=&#8221;1404&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-banner spy1&#8243; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#343840&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221; el_class=&#8221;smb-tiny&#8221;]\n<h5>For Home<\/h5>\n[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221;]\n<h1>CREO entrance doors<\/h1>\n[\/vc_column_text][vc_column_text text_direction=&#8221;default&#8221; el_class=&#8221;sub-heading&#8221;]Combining high thermal insulation and safety with your vision of the home.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;spy1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221; max_width=&#8221;650&#8243;]CREO \u2013 a door model featuring only the best qualities. Made of durable aluminium, incredibly warm and safe. It offers unlimited customisation possibilities, a broad selection of accessories, as well as smart and keyless solutions. You can match its design to that of your garage door, windows, and fence.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;page-inner-slider&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<style type=\"text\/css\">#nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { min-height: 400px; } #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: calc( 500 * 100vw \/ 1600 ); } <\/style><div data-midnight=\"nectar-slider\" class=\"parallax_slider_outer \"><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"true\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"7000\" data-parallax=\"true\" data-parallax-disable-mobile=\"true\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"ken_burns\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"500\" data-min-height=\"400\" data-arrows=\"false\" data-bullets=\"true\" data-bullet_style=\"see_through_ar_visualized\" data-bullet_position=\"right\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"bottom\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/dev.novia-doors.com\/wp-content\/uploads\/2024\/09\/8c053db9-c6ec-4c6c-8dbb-838598b3d4ed.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h3 class=\"ns-heading-el\">Warm, quiet, and functional<\/h3><p  ><span>High thermal insulation parameters minimise energy losses at home, ensuring warmth in the winter and pleasant coolness in the summer. A tight door is also the best protection against noise. We remember about your comfort, which is why we add a set of 7 keys to the CREO door as standard!<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;spt1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h2>Door leaf structure<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal&#8221;][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;A warm and sound-insulating leaf&#8221;][vc_column_text text_direction=&#8221;default&#8221;]with solutions for the best durability.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Three-point automatic lock&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\u2013 ensures security.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Certified anti-burglary lock cylinder&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\u2013 security backed up by convenience of use.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Convenient opening systems&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\u2013 also in a version without a key.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;A set of 5 permanent and 2 temporary keys&#8221;][vc_column_text text_direction=&#8221;default&#8221;]as standard.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Threshold with a thermal break and thermal widening&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\u2013 for perfect and warm installation.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Compensation mats&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\u2013 for additional sound insulation and preventing deflection.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Sealed so well&#8221;][vc_column_text text_direction=&#8221;default&#8221;]that they can be fitted in areas without a roof.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;The opening frame and leaf&#8221;][vc_column_text text_direction=&#8221;default&#8221;]provide proper thermal insulation and durability.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Glass pane&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\u2013 a safe quadruple-glazed unit.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Roller or concealed hinges&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\u2013 aesthetics and reliability.[\/vc_column_text][\/toggle][\/toggles][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1461&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_video_player_self_hosted video_mp4=&#8221;http:\/\/dev.novia-doors.com\/wp-content\/uploads\/2024\/09\/0970fee5-be5f-4525-ac2c-c1b47c125c35.mp4&#8243; video_image=&#8221;1471&#8243; align=&#8221;center&#8221; player_functionality=&#8221;lightbox&#8221; play_button_style=&#8221;default&#8221; play_button_color=&#8221;#000000&#8243; play_button_icon_color=&#8221;#d9d800&#8243; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; advanced_gradient_display_type=&#8221;linear&#8221; video_lightbox_url=&#8221;http:\/\/dev.novia-doors.com\/wp-content\/uploads\/2024\/09\/0970fee5-be5f-4525-ac2c-c1b47c125c35.mp4&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;spt1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h2>The CREO collection<\/h2>\n<p>Fall in love with their uniqueness and modernity. Select those that match your vision in every detail.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25&#8243;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;5&#8243; desktop_small_cols_flickity=&#8221;4&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;none&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871749-3&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871749-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1448&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 801<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871785-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871786-1&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1449&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 802<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871825-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871826-3&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1450&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 803<\/h4>\n[\/fancy_box][\/item][\/carousel][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;5&#8243; desktop_small_cols_flickity=&#8221;4&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;none&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871852-9&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871852-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1445&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 701<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871880-9&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871881-4&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1446&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 702<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871914-4&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871915-2&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1447&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 703<\/h4>\n[\/fancy_box][\/item][\/carousel][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;5&#8243; desktop_small_cols_flickity=&#8221;4&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;none&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871950-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871951-6&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1442&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 601<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871970-4&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871971-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1443&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 602<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125871991-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125871991-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1444&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 603<\/h4>\n[\/fancy_box][\/item][\/carousel][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;5&#8243; desktop_small_cols_flickity=&#8221;4&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;none&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872023-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872023-3&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1438&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 501<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872054-1&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872055-3&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1439&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 502<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872144-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872145-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1440&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 503<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872179-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872180-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1441&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 504<\/h4>\n[\/fancy_box][\/item][\/carousel][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;5&#8243; desktop_small_cols_flickity=&#8221;4&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;touch_total&#8221; flickity_touch_total_style=&#8221;default&#8221; flickity_touch_total_hide_indicator=&#8221;true&#8221; flickity_touch_total_icon_color=&#8221;default&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872221-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872222-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1430&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 401<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872246-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872247-4&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1431&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 402<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872269-9&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872269-6&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1432&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 403<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872291-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872292-4&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1433&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 411<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872309-1&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872310-3&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1434&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 412<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872334-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872334-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1435&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 413<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872357-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872357-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1436&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 414<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872375-1&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872375-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1437&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 415<\/h4>\n[\/fancy_box][\/item][\/carousel][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;5&#8243; desktop_small_cols_flickity=&#8221;4&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;touch_total&#8221; flickity_touch_total_style=&#8221;default&#8221; flickity_touch_total_hide_indicator=&#8221;true&#8221; flickity_touch_total_icon_color=&#8221;default&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872434-2&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872434-1&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1406&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 310<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872456-4&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872457-2&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1407&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 311<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872474-2&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872474-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1408&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 312<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872489-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872490-2&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1409&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 313<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872513-7&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872513-1&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1410&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 314<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872536-9&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872537-2&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1411&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 315<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872553-7&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872553-2&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1412&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 316<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872576-4&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872577-1&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1413&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 317<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872595-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872595-10&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1414&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 318<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872619-2&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872619-10&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1415&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 319<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872643-0&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872644-8&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1416&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 321<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872679-3&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872679-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1417&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 322<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872704-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872704-8&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1418&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 323<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872722-3&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872722-4&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1419&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 324<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872742-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872742-3&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1420&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 325<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872767-0&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872768-3&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1421&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 326<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872792-1&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872792-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1422&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 331<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872818-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872818-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1423&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 336<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872847-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872854-5&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1424&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 344<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872878-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872878-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1425&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 345<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872899-9&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872900-7&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1426&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 347<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872928-4&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872929-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1427&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 349<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872955-3&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872956-0&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1428&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 350<\/h4>\n[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1726125872977-2&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1726125872978-2&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;1429&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;300&#8243; min_height_tablet=&#8221;550&#8243; image_size=&#8221;large&#8221;]\n<h4>CREO | 360<\/h4>\n[\/fancy_box][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;35&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<h2>Colour scheme<\/h2>\n<p>Different finishing technologies give the CREO doors a unique look. Mat structure colours from the RAL and DECOR palettes provide exceptional visual effects, while film coating makes it possible to obtain an interesting texture.[\/vc_column_text][tabbed_section style=&#8221;minimal&#8221; tab_change_animation=&#8221;fade&#8221; alignment=&#8221;left&#8221; spacing=&#8221;default&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; cta_button_style=&#8221;accent-color&#8221; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Standard colours&#8221; id=&#8221;1726125873135-8&#8243; tab_id=&#8221;1726125873136-7&#8243;][image_with_animation image_url=&#8221;1453&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][image_with_animation image_url=&#8221;1452&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;DECOR colours&#8221; id=&#8221;1726125873187-1&#8243; tab_id=&#8221;1726125873187-4&#8243;][image_with_animation image_url=&#8221;1454&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Film coatings&#8221; id=&#8221;1726125873204-6&#8243; tab_id=&#8221;1726125873205-5&#8243;][image_with_animation image_url=&#8221;1455&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][image_with_animation image_url=&#8221;1456&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][image_with_animation image_url=&#8221;1457&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Home Inclusive 2.0&#8243; id=&#8221;1726125873287-3&#8243; tab_id=&#8221;1726125873287-3&#8243;][image_with_animation image_url=&#8221;1458&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/tab][\/tabbed_section][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1391&#8243; bg_image_phone=&#8221;1404&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-banner spy1&#8243; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#343840&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1401","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":41,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages\/1401\/revisions"}],"predecessor-version":[{"id":1503,"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/pages\/1401\/revisions\/1503"}],"wp:attachment":[{"href":"https:\/\/dev.novia-doors.com\/en\/wp-json\/wp\/v2\/media?parent=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}